{"id":273,"count":1,"description":"","link":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/","name":"Ryszard Leoszewski","slug":"ryszard-leoszewski","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ryszard Leoszewski - Marek Koszur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ryszard Leoszewski - Marek Koszur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/\" \/>\n<meta property=\"og:site_name\" content=\"Marek Koszur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/koszur.net\\\/index.php\\\/tag\\\/ryszard-leoszewski\\\/\",\"url\":\"https:\\\/\\\/koszur.net\\\/index.php\\\/tag\\\/ryszard-leoszewski\\\/\",\"name\":\"Ryszard Leoszewski - Marek Koszur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/koszur.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/koszur.net\\\/index.php\\\/tag\\\/ryszard-leoszewski\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/koszur.net\\\/index.php\\\/tag\\\/ryszard-leoszewski\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/koszur.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ryszard Leoszewski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/koszur.net\\\/#website\",\"url\":\"https:\\\/\\\/koszur.net\\\/\",\"name\":\"Marek Koszur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/koszur.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ryszard Leoszewski - Marek Koszur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/","og_locale":"pl_PL","og_type":"article","og_title":"Ryszard Leoszewski - Marek Koszur","og_url":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/","og_site_name":"Marek Koszur","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/","url":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/","name":"Ryszard Leoszewski - Marek Koszur","isPartOf":{"@id":"https:\/\/koszur.net\/#website"},"breadcrumb":{"@id":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/koszur.net\/index.php\/tag\/ryszard-leoszewski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/koszur.net\/"},{"@type":"ListItem","position":2,"name":"Ryszard Leoszewski"}]},{"@type":"WebSite","@id":"https:\/\/koszur.net\/#website","url":"https:\/\/koszur.net\/","name":"Marek Koszur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/koszur.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/koszur.net\/index.php\/wp-json\/wp\/v2\/tags\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koszur.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/koszur.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/koszur.net\/index.php\/wp-json\/wp\/v2\/posts?tags=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}